{"id":975,"date":"2023-09-29T11:06:53","date_gmt":"2023-09-29T03:06:53","guid":{"rendered":"https:\/\/www.dmsteels.com\/?p=975"},"modified":"2024-11-22T14:56:53","modified_gmt":"2024-11-22T06:56:53","slug":"overseas-visit%ef%bd%9cdaming-international-visits-sumitomo-corporation-chile","status":"publish","type":"post","link":"https:\/\/www.dmsteels.com\/es\/overseas-visit%ef%bd%9cdaming-international-visits-sumitomo-corporation-chile\/","title":{"rendered":"Visita al extranjero\uff5cDaming International visita Sumitomo Corporation Chile"},"content":{"rendered":"<p>El 29 de septiembre, hora local, Zhou Keming, Presidente del Consejo de Administraci\u00f3n de Daming International, Wang Xi, Director General de Daming Energy Equipment, Wang Xuming, Asistente del Presidente del Consejo de Administraci\u00f3n y Subdirector General de Importaci\u00f3n y Exportaci\u00f3n de Daming International, Yao Lei, Subdirector del Departamento de Ventas de Daming Energy Equipment, y Shao Ke, Asistente del Director del Departamento de Importaci\u00f3n y Exportaci\u00f3n de Daming, viajaron a Chile para visitar Sumitomo Corporation y mantener intercambios.<br \/>\nEl Sr. Takashi Onda, Presidente de Sumitomo Corporation Chile, y el Sr. Carlos Espinosa, Gerente General del Departamento de Metales, Medio Ambiente e Infraestructura de la Regi\u00f3n de Am\u00e9rica Latina, recibieron calurosamente la visita.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-976 size-full\" title=\"Visita al extranjero\uff5cDaming International visita Sumitomo Corporation Chile\" src=\"https:\/\/www.dmsteels.com\/wp-content\/uploads\/2023\/10\/08cee64ed2d3b08b5675f2b2b270e4cd.jpg\" alt=\"Visita al extranjero\uff5cDaming International visita Sumitomo Corporation Chile\" width=\"1080\" height=\"538\" srcset=\"https:\/\/www.dmsteels.com\/wp-content\/uploads\/2023\/10\/08cee64ed2d3b08b5675f2b2b270e4cd.jpg 1080w, https:\/\/www.dmsteels.com\/wp-content\/uploads\/2023\/10\/08cee64ed2d3b08b5675f2b2b270e4cd-300x149.jpg 300w, https:\/\/www.dmsteels.com\/wp-content\/uploads\/2023\/10\/08cee64ed2d3b08b5675f2b2b270e4cd-1024x510.jpg 1024w, https:\/\/www.dmsteels.com\/wp-content\/uploads\/2023\/10\/08cee64ed2d3b08b5675f2b2b270e4cd-768x383.jpg 768w\" sizes=\"auto, (max-width: 1080px) 100vw, 1080px\" \/><\/p>\n<p>Durante el intercambio, el Sr. Zhou Keming, Presidente de Sumitomo Corporation, present\u00f3 la historia general de desarrollo del Grupo, las ventajas de los grupos de equipos, los casos de servicios industriales y el plan de distribuci\u00f3n de inversiones a medio y largo plazo del Grupo en los mercados de ultramar. Dijo que Sumitomo Corporation ha invertido en una amplia gama de campos en Am\u00e9rica del Sur, incluyendo la miner\u00eda, la energ\u00eda y la infraestructura, y que las dos partes tienen una amplia perspectiva de cooperaci\u00f3n en \u00e1reas clave.<\/p>\n<p>El presidente Onda acogi\u00f3 calurosamente la visita del equipo de Daming y reconoci\u00f3 la perfecta capacidad de procesamiento y fabricaci\u00f3n y el avanzado modelo de gesti\u00f3n de f\u00e1brica del Grupo Daming. En el futuro, las dos partes intensificar\u00e1n los intercambios en los campos del procesamiento de materiales y la fabricaci\u00f3n de equipos, y llevar\u00e1n a cabo una cooperaci\u00f3n multidimensional teniendo en cuenta las caracter\u00edsticas del mercado local.<\/p>","protected":false},"excerpt":{"rendered":"<p>On September 29, local time, Zhou Keming, Chairman of the Board of Directors of Daming International, Wang Xi, General Manager of Daming Energy Equipment, Wang Xuming, Assistant to the Chairman of the Board of Directors and Deputy General Manager of Import and Export of Daming International, Yao Lei, Deputy Director of the Sales Department of [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":976,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-975","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-daming-news"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.dmsteels.com\/es\/wp-json\/wp\/v2\/posts\/975","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dmsteels.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.dmsteels.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.dmsteels.com\/es\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dmsteels.com\/es\/wp-json\/wp\/v2\/comments?post=975"}],"version-history":[{"count":0,"href":"https:\/\/www.dmsteels.com\/es\/wp-json\/wp\/v2\/posts\/975\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.dmsteels.com\/es\/wp-json\/wp\/v2\/media\/976"}],"wp:attachment":[{"href":"https:\/\/www.dmsteels.com\/es\/wp-json\/wp\/v2\/media?parent=975"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.dmsteels.com\/es\/wp-json\/wp\/v2\/categories?post=975"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.dmsteels.com\/es\/wp-json\/wp\/v2\/tags?post=975"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}